{"id":815,"date":"2020-11-18T10:22:27","date_gmt":"2020-11-18T09:22:27","guid":{"rendered":"http:\/\/leshistoiresduplacard.fr\/?p=815"},"modified":"2020-11-18T10:22:27","modified_gmt":"2020-11-18T09:22:27","slug":"chapitre-2-a-la-recherche-du-commissariat-perdu","status":"publish","type":"post","link":"https:\/\/leshistoiresduplacard.fr\/index.php\/2020\/11\/18\/chapitre-2-a-la-recherche-du-commissariat-perdu\/","title":{"rendered":"Chapitre 2 &#8211; A la recherche du commissariat perdu"},"content":{"rendered":"<p class=\"alinea\">\u201cVous \u00eates arriv\u00e9 \u00e0 destination&nbsp;!\u201d Mon p\u00e8re ob\u00e9it docilement au GPS (qui avait un peu la voix de gogol, c\u2019est \u00e9trange) et gara la voiture le long du trottoir.<\/p>\n<p class=\"alinea\">\u2013 <em>Papa, tu es vraiment s\u00fbr que c\u2019est l\u00e0&nbsp;?<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Bien s\u00fbr que je suis s\u00fbr, on peut se fier au GPS, il est pr\u00e9cis \u00e0 la seconde et au m\u00e8tre pr\u00e8s&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Je regardais autour de nous, tout en me demandant si Albert Einstein, mon p\u00e8re et moi avions la m\u00eame notion de l\u2019espace-temps.<\/p>\n<p class=\"alinea\">Tout ce que je voyais dans un rayon de 1500 millim\u00e8tres (je vous laisse convertir en m\u00e8tre), c\u2019\u00e9tait une barri\u00e8re avec marqu\u00e9 \u00ab\u00a0Interdit au public\u00a0\u00bb qu\u2019une personne en tenue de chantier \u00e9tait en train de man\u0153uvrer. J\u2019en profitais pour me moquer gentiment&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Regarde papa, un policier avec un marteau piqueur et un casque jaune sur la t\u00eate&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Mon p\u00e8re, qui semblait d\u00e9j\u00e0 moins s\u00fbr d\u2019en \u00eatre s\u00fbr, r\u00e9fl\u00e9chit quelques secondes, et finit par \u00e9mettre une hypoth\u00e8se&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Il se pourrait fort bien que la carte du GPS ne soit pas tout-\u00e0-fait \u00e0 jour, nonobstant le fait que je l\u2019ai achet\u00e9e la semaine derni\u00e8re et que le vendeur, que je retournerais voir pour lui exprimer en terme choisi ma fa\u00e7on de penser, m\u2019a garanti la fra\u00eecheur des informations pour \u201c\u00e0 peine\u201d dix euros de plus<\/em>, et il a claqu\u00e9 la porti\u00e8re en guise de point finale, VVRANCK (c\u2019est ce que j\u2019ai trouv\u00e9 de plus approchant pour un bruit de porti\u00e8re qui claque)<\/p>\n<p class=\"alinea\">Lorsque mon p\u00e8re est agac\u00e9, il a tendance \u00e0 faire des phrases t\u00e9lescopiques et l\u00e0, je crois qu\u2019il commen\u00e7ait \u00e0 \u00eatre plus que \u00ab\u00a0l\u00e9g\u00e8rement\u00a0\u00bb agac\u00e9 (mais moins que \u00ab\u00a0vraiment\u00a0\u00bb, on va dire \u00ab\u00a0moyennement\u00a0\u00bb si cela vous convient, et si \u00e7a ne vous convient pas, c\u2019est la m\u00eame chose, parce que l\u00e0, moi aussi je commence \u00e0 \u00eatre agac\u00e9e et \u00e0 faire des phrases \u00e0 rallonge).<\/p>\n<p><img src=\"https:\/\/leshistoiresduplacard.fr\/wp-content\/uploads\/2020\/11\/cha2s2i1.jpg\"><\/p>\n<p class=\"separateur\">***<\/p>\n<p class=\"alinea\">Nous \u00e9tions tous les deux sur le trottoir, scrutant l\u2019horizon comme deux indiens d\u00e9plum\u00e9s, \u00e0 la recherche d\u2019un indice pouvant nous mettre sur la piste du commissariat, lorsqu\u2019un homme casqu\u00e9 de jaune s\u2019est approch\u00e9 de nous pour nous interpeller d\u2019un&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Police, vos papiers s\u2019il vous pla\u00eet&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Je regardais mon p\u00e8re, stup\u00e9faite. Quoi&nbsp;? Finalement les policiers se baladent vraiment avec un marteau piqueur et un casque jaune sur la t\u00eate&nbsp;?<\/p>\n<p class=\"alinea\">\u2013 <em>D\u00e9sol\u00e9, a ajout\u00e9 l\u2019homme en jaune,<\/em> dans un grand sourire,<em> j\u2019ai pas pu m\u2019emp\u00eacher en vous \u00e9coutant. Pas d\u2019panique la police nationale n\u2019a pas chang\u00e9 d\u2019k\u00e9pi, elle a juste chang\u00e9 d\u2019bocal.<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Euh\u2026 vous voulez dire de local&nbsp;?<\/em> a demand\u00e9 mon p\u00e8re.<\/p>\n<p class=\"alinea\">\u2013 <em>C\u2019est \u00e7a&nbsp;! Les anciens bocaux ont \u00e9t\u00e9 ras\u00e9 pour faire place \u00e0 du neuf, et en attendant, toute la brigade a \u00e9t\u00e9 transvas\u00e9e dans des b\u00e2timents temporaires un peu plus haut dans la rue<\/em>, et il a indiqu\u00e9 une direction.<\/p>\n<p class=\"alinea\">Mon p\u00e8re l\u2019a remerci\u00e9 chaleureusement, mais avant de partir il a demand\u00e9&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Et, par curiosit\u00e9, les travaux ont commenc\u00e9 quand&nbsp;?<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Plus d\u2019un an m\u2019sieur&nbsp;! C\u2019est que, pour faire les choses bien, il faut prendre son temps pas vrai&nbsp;?<\/em><\/p>\n<p class=\"alinea\">Je regardais derri\u00e8re la barri\u00e8re, et n\u2019y voyais qu\u2019un grand trou. Mwouai, pas la peine d\u2019avoir des marteaux piqueurs, si c\u2019est pour creuser \u00e0 la p\u2019tite cuill\u00e8re.<\/p>\n<p><img src=\"https:\/\/leshistoiresduplacard.fr\/wp-content\/uploads\/2020\/11\/cha2s2i2.jpg\"><\/p>\n<p class=\"separateur\">***<\/p>\n<p class=\"alinea\">Je ne sais pas \u00e0 quoi je m\u2019attendais, mais je sais \u00e0 quoi je ne m\u2019attendais pas, et c\u2019est justement ce qui nous attendait lorsqu\u2019on est arriv\u00e9 devant le commissariat de police (relisez cette phrase \u00e0 l\u2019envers pour d\u00e9faire les n\u0153uds qu\u2019elle a d\u00fb provoquer dans votre cerveau).<\/p>\n<p class=\"alinea\">En lieu et place d\u2019un b\u00e2timent rutilant drap\u00e9 des couleurs de la r\u00e9publique, auquel tout bon citoyen est en droit de s\u2019attendre (ici, faites r\u00e9sonner la Marseillaise dans votre t\u00eate), nous nous sommes retrouv\u00e9s devant un empilement de blocs de b\u00e9ton qui avaient l\u2019air d\u2019avoir \u00e9t\u00e9 jet\u00e9 l\u00e0, faute de place \u00e0 la d\u00e9chetterie la plus proche.<\/p>\n<p class=\"alinea\">Mon p\u00e8re m\u2019a lanc\u00e9 un regard de homard, le genre qui apr\u00e8s s\u2019\u00eatre demand\u00e9 o\u00f9 il \u00e9tait tomb\u00e9, se rend compte que c\u2019est dans une casserole d\u2019eau bouillante.<\/p>\n<p class=\"alinea\">\u2013 <em>Papa, je te rappelle que je suis ta fille, et que c\u2019est toi qui es cens\u00e9 me rassurer.<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Euh, Lola, ne t\u2019inqui\u00e8te pas. Tu sais parfois la premi\u00e8re impression n\u2018est pas la bonne, l\u2019ext\u00e9rieur ne refl\u00e8te pas toujours la beaut\u00e9 int\u00e9rieure<\/em>, et l\u00e0 il a sembl\u00e9 chercher un exemple pour appuyer sa d\u00e9monstration. Je suis venu \u00e0 son secours&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Un peu comme ce qu\u2019a d\u00fb penser maman quand elle t\u2019a rencontr\u00e9&nbsp;?<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Euh\u2026 oui&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Regard de homard&nbsp;!<\/p>\n<p><img src=\"https:\/\/leshistoiresduplacard.fr\/wp-content\/uploads\/2020\/11\/cha2s2i3.jpg\"><\/p>\n<p class=\"separateur\">***<\/p>\n<p class=\"alinea\">On s\u2019est donc retrouv\u00e9 devant l\u2019entr\u00e9e du b\u00e2timent principale. Papa a regard\u00e9 \u00e0 droite, puis \u00e0 gauche, esp\u00e9rant trouver une sonnette ou quelque chose ressemblant \u00e0 un bouton d\u2019appel.<\/p>\n<p class=\"alinea\">\u2013 <em>Bon sang, comment on est cens\u00e9 rentrer&nbsp;? Il y a forc\u00e9ment un moyen&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Pendant qu\u2019il r\u00e9fl\u00e9chissait, je faisais le tour du propri\u00e9taire. En plus des diff\u00e9rents parall\u00e9l\u00e9pip\u00e8des (d\u00e9sol\u00e9 d\u2019\u00e9voquer de p\u00e9nibles souvenirs de cours de g\u00e9om\u00e9trie) qui constituaient l\u2019architecture du lieu, il y avait, sur le terrain vaguement am\u00e9nag\u00e9 en parking, une dizaine de v\u00e9hicules, dont le seul point commun \u00e9tait un \u00e9tat de d\u00e9labrement qui aurait valu une mise \u00e0 la casse imm\u00e9diate, s\u2019ils n\u2019avaient \u00e9t\u00e9 surmont\u00e9s d\u2019un gyrophare.<\/p>\n<p class=\"alinea\">\u2013 <em>Il doit y avoir un syst\u00e8me de protection tr\u00e8s sophistiqu\u00e9<\/em>, a fini par dire mon p\u00e8re,<em> c\u2019est \u00e9vident qu\u2019on ne rentre pas dans un commissariat comme dans un moulin.<\/em><\/p>\n<p class=\"alinea\">Je me suis approch\u00e9e \u00e0 mon tour et me suis coll\u00e9e \u00e0 la vitre pour essayer de voir \u00e0 l\u2019int\u00e9rieur du moulin, euh\u2026 du commissariat.<\/p>\n<p class=\"alinea\">\u2013 <em>\u00c9videmment elle est teint\u00e9e<\/em>, a ajout\u00e9 papa<em>, s\u00e9curit\u00e9 oblige, un commissariat c\u2019est un peu une forteresse&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Je retirais alors mes mains pour lui montrer le type de \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb employ\u00e9e.<\/p>\n<p class=\"alinea\">\u2013 <em>Je crois que c\u2019est juste\u2026 de la crasse&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Mon nettoyage involontaire avait au moins eu le m\u00e9rite de nous permettre de voir \u00e0 l\u2019int\u00e9rieur.<\/p>\n<p class=\"alinea\">\u2013 <em>Il me semble voir un petit panneau&nbsp;!<\/em> s\u2019est exclam\u00e9 papa,<em> Oui&nbsp;! il y a un code \u00e9crit dessus, c\u2019est le num\u00e9ro \u00e0 taper. Il doit y avoir un clavier pas loin.<\/em><\/p>\n<p class=\"alinea\">Je me suis pench\u00e9e moi aussi pour voir le message et j\u2019ai demand\u00e9&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>Papa, je peux t\u2019emprunter ton tel\u2019&nbsp;?<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Euh, oui, si tu veux, mais si tu m\u2019aidais plut\u00f4t \u00e0 chercher le digicode, en g\u00e9n\u00e9ral c\u2019est juste \u00e0 quelques centim\u00e8tres\u2026<\/em> et il a recommenc\u00e9 \u00e0 fureter autour de la porte.<\/p>\n<p class=\"alinea\">Au bout de quelques secondes, voyant que j\u2019\u00e9tais en conversation, il s\u2019est approch\u00e9.<\/p>\n<p class=\"alinea\">\u2013 <em>Lola, \u00e0 qui es-tu en train de\u2026<\/em> et la porte s\u2019est ouverte comme par magie.<\/p>\n<p class=\"alinea\">Ce n\u2019est pas la phrase de mon p\u00e8re qui l\u2019a ouverte, \u00ab\u00a0s\u00e9same ouvre-toi\u00a0\u00bb, je veux bien mais&nbsp;: \u00ab\u00a0Lola \u00e0 qui es-tu en train de \u2026\u00a0\u00bb, \u00e7a laisse \u00e0 d\u00e9sirer comme phrase magique non&nbsp;?<\/p>\n<p class=\"alinea\">Les deux battants de la porte vitr\u00e9e ont donc gliss\u00e9, pas de mani\u00e8re naturelle, ni surnaturelle, mais plut\u00f4t\u2026 sous-naturel, car de l\u2019autre c\u00f4t\u00e9, point de bon g\u00e9nie mais&#8230;<\/p>\n<p class=\"alinea\">\u2013 <em>Eh, mais c\u2019est notre inspecteur&nbsp;!<\/em> s\u2019est exclam\u00e9 mon p\u00e8re.<\/p>\n<p class=\"alinea\">Et pour une fois, il n\u2019avait pas compl\u00e8tement tort&nbsp;!<\/p>\n<p class=\"separateur\">***<\/p>\n<p class=\"alinea\">Pas compl\u00e8tement, parce que si l\u2019homme qui nous faisait face ressemblait bien au petit inspecteur l\u00e9g\u00e8rement envelopp\u00e9, il lui dissemblait (non c\u2019est pas un mot que je viens d\u2019inventer) suffisamment pour que ce ne soit pas lui.<\/p>\n<p class=\"alinea\">Il avait le visage rougi par l\u2019effort&nbsp;:<\/p>\n<p class=\"alinea\">\u2013 <em>D\u00e9sol\u00e9 m\u2019sieurs dame, la porte est en panne, il faut l\u2019ouvrir manuellement depuis l\u2019int\u00e9rieur, c\u2019est pour \u00e7a que j\u2019ai mis le petit panneau. J\u2019\u00e9tais pas s\u00fbr que tout le monde comprenne qu\u2019il faille appeler le 17 pour avoir le commissariat et demander qu\u2019on vienne ouvrir, mais apparemment \u00e7a marche pas trop mal&nbsp;!<\/em><\/p>\n<p class=\"alinea\">\u2013 <em>Euh\u2026 oui<\/em>, a dit mon p\u00e8re en me regardant<em>, c\u2019\u00e9tait \u00e9vident bien s\u00fbr<\/em>, et il m\u2019a fait un clin d\u2019\u0153il rat\u00e9.<\/p>\n<p class=\"alinea\">\u2013 <em>Par contre<\/em>, a-t-il ajout\u00e9 en tra\u00eenant un doigt sur la vitre<em>, je crois qu\u2019un zeste de m\u00e9nage ne serait pas de trop&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Le policier a fait mine d\u2019\u00eatre \u00e9tonn\u00e9,<\/p>\n<p class=\"alinea\">\u2013 <em>Ah bon&nbsp;? Pourtant il vient d\u2019\u00eatre fait, il y a peine 3 mois&nbsp;!<\/em><\/p>\n<p class=\"alinea\">Je ne me permettrais pas de juger, c\u2019est \u00e0 peu de chose pr\u00e9s, la derni\u00e8re fois que j\u2019avais rang\u00e9 ma chambre.<\/p>\n<p><img src=\"https:\/\/leshistoiresduplacard.fr\/wp-content\/uploads\/2020\/11\/cha2s2i4.jpg\"><\/p>\n<p class=\"separateur\">***<\/p>\n<p class=\"alinea\">Une fois \u00e0 l\u2019int\u00e9rieur de la \u201cforteresse\u201d, la normalit\u00e9 a sembl\u00e9 reprendre ses droits. Il y avait un large vestibule (rien \u00e0 voir avec la bulle dans laquelle votre poisson range sa veste rouge apr\u00e8s une dure journ\u00e9e de travail), avec en son centre un bureau flambant neuf en arc de cercle.<\/p>\n<p class=\"alinea\">L\u2019agent nous a devanc\u00e9 pour aller se poster fi\u00e8rement derri\u00e8re son office, et nous a accueillie comme s\u2019il n\u2019avait jamais boug\u00e9 de son poste.<\/p>\n<p class=\"alinea\">\u2013 <em>M\u2019sieur dame, bienvenue au commissariat principal, je suis l\u2019agent d\u2019accueil Rodolphe, que puis-je pour vous&nbsp;!<\/em><\/p>\n<p class=\"alinea\">A l\u2019audition de cette simple phrase, j\u2019ai eu l\u2019impression qu\u2019on venait de secouer la boule \u00e0 neige qui me sert de mati\u00e8re grise. Une avalanche de questions est venue s\u2019\u00e9craser \u00e0 l\u2019arri\u00e8re de mon sourcil gauche, que je commen\u00e7ais \u00e0 gratter fr\u00e9n\u00e9tiquement.<\/p>\n<p class=\"alinea\">Commissariat principal&nbsp;? Si \u00e7a s\u2019\u00e9tait le commissariat principal, le secondaire \u00e9tait en quoi&nbsp;? En papier m\u00e2ch\u00e9&nbsp;? Et le tertiaire&nbsp;? En bouse de yak s\u00e9ch\u00e9&nbsp;? Et les autres&nbsp;? (Peut-\u00eatre un assemblage h\u00e9t\u00e9roclite de paille et de crotte de nez).<\/p>\n<p class=\"alinea\">Et puis Rodolphe&nbsp;? Comment pouvait-on encore s\u2019appeler Rodolphe au 21 si\u00e8cle&nbsp;? De tous les pr\u00e9noms disponibles, je crois bien qu\u2019on ne pouvait en trouver de pire&nbsp;! (D\u00e9sol\u00e9 pour mes lecteurs ou lectrices qui s\u2019appellent Rodolphe, vous pouvez remplacer tous les Rodolphe qui suivent par un pr\u00e9nom de votre choix\u2026 du moment qu\u2019il se termine par \u00ab\u00a0lphe\u00a0\u00bb&nbsp;!)<\/p>\n<p class=\"alinea\">Et ensuite, comment ce faisait-il que cet atrocement pr\u00e9nomm\u00e9 Rodolphe, ressemble \u00e0 ce point \u00e0 mon inspecteur&nbsp;! Est-ce qu\u2019un peu comme des moules \u00e0 cake, il y avait des moules \u00e0 policier&nbsp;?<\/p>\n<p class=\"alinea\">Du fin fond de mes pens\u00e9es me parvint alors une voix. \u00c9tait-ce la voix de la sagesse&nbsp;? \u00c9tait-ce la voix de la connaissance&nbsp;? Non, juste la voix de mon p\u00e8re, qui r\u00e9pondait \u00e0 l\u2019agent qui demandait la raison de notre pr\u00e9sence.<\/p>\n<p class=\"alinea\">\u2013 <em>Ah mais oui&nbsp;!<\/em> s\u2019exclama \u201cRodolphe\u201d,<em> je vois parfaitement qui vous \u00eates, c\u2019est mon fr\u00e8re a\u00een\u00e9 qui est en charge de l\u2019enqu\u00eate avec l\u2019inspectrice.<\/em><\/p>\n<p class=\"alinea\">Woua ! si je m\u2019attendais \u00e0 \u00e7a, mon agent avait un fr\u00e8re policier&nbsp;!<\/p>\n<p class=\"alinea\">\u2013 <em>Bureau 112 au 1er, c\u2019est l\u00e0 que vous trouverez mon fr\u00e8re&nbsp;: Adolphe.<\/em><\/p>\n<p class=\"alinea\">Arghh&nbsp;! les parents de Rodolphe avaient r\u00e9ussi \u00e0 trouver encore pire&nbsp;!<\/p>\n<p class=\"alinea\">Je crois que pendant quelques secondes, de battre mon c\u0153ur s\u2019est arr\u00eat\u00e9.<\/p>\n<p><img src=\"https:\/\/leshistoiresduplacard.fr\/wp-content\/uploads\/2020\/11\/cha2s2i5.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cVous \u00eates arriv\u00e9 \u00e0 destination&nbsp;!\u201d Mon p\u00e8re ob\u00e9it docilement au GPS (qui avait un peu la voix de gogol, c\u2019est \u00e9trange) et gara la voiture le long du trottoir. \u2013 Papa, tu es vraiment s\u00fbr que c\u2019est l\u00e0&nbsp;? \u2013 Bien s\u00fbr que je suis s\u00fbr, on peut se fier au GPS, il est pr\u00e9cis \u00e0 &hellip; <a href=\"https:\/\/leshistoiresduplacard.fr\/index.php\/2020\/11\/18\/chapitre-2-a-la-recherche-du-commissariat-perdu\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Chapitre 2 &#8211; A la recherche du commissariat perdu<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/posts\/815"}],"collection":[{"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/comments?post=815"}],"version-history":[{"count":11,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/posts\/815\/revisions"}],"predecessor-version":[{"id":844,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/posts\/815\/revisions\/844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/media\/840"}],"wp:attachment":[{"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/media?parent=815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/categories?post=815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leshistoiresduplacard.fr\/index.php\/wp-json\/wp\/v2\/tags?post=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}